{"id":24883,"date":"2025-09-01T13:29:09","date_gmt":"2025-09-01T12:29:09","guid":{"rendered":"https:\/\/calerodiving.com\/probieren-sie-das-tauchen-aus\/"},"modified":"2026-06-10T10:52:31","modified_gmt":"2026-06-10T09:52:31","slug":"try-scuba-diving","status":"publish","type":"page","link":"https:\/\/calerodiving.com\/de\/try-scuba-diving\/","title":{"rendered":"Try Scuba Diving"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"24883\" class=\"elementor elementor-24883 elementor-20282\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-009eb9a e-flex e-con-boxed e-con e-parent\" data-id=\"009eb9a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-64e2daa e-con-full e-flex e-con e-child\" data-id=\"64e2daa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ebadaf elementor-widget elementor-widget-image\" data-id=\"1ebadaf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-1030x687.jpg\" class=\"attachment-large size-large wp-image-20250\" alt=\"\" srcset=\"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-1030x687.jpg 1030w, https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-300x200.jpg 300w, https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-768x512.jpg 768w, https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-1536x1024.jpg 1536w, https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-2048x1365.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8ed3d5e e-con-full e-flex e-con e-child\" data-id=\"8ed3d5e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-993bdc1 e-con-full e-flex e-con e-child\" data-id=\"993bdc1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3e1d005 elementor-widget elementor-widget-html\" data-id=\"3e1d005\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/calerodiving.com\/de\/sporttauchkurse\/#baptisms\" class=\"tag-button\">Anf\u00e4ngerkurse<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cb381d elementor-widget elementor-widget-heading\" data-id=\"4cb381d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Try Scuba Diving<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19fa76e e-flex e-con-boxed e-con e-parent\" data-id=\"19fa76e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a8907d2 e-con-full e-flex e-con e-child\" data-id=\"a8907d2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-0fd81f7 e-con-full e-flex e-con e-child\" data-id=\"0fd81f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-794723b elementor-widget elementor-widget-heading\" data-id=\"794723b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dein erster Schritt in die Unterwasserwelt.\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6e459a elementor-widget elementor-widget-text-editor\" data-id=\"a6e459a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"section-list\">\n\n<h3>Programm\u00fcbersicht:<\/h3>\n\n<p>SSI Try Scuba ist das perfekte erste Taucherlebnis \u2013 dein allererstes Mal unter Wasser und sehr wahrscheinlich nicht dein letztes.<\/p>\n\n<p>Wir zeigen dir die Tauchausr\u00fcstung, erkl\u00e4ren dir die wichtigsten Grundregeln des Ger\u00e4tetauchens und die wichtigsten Unterwasser-Handzeichen.<\/p>\n\n<p>Nach der Einf\u00fchrung startest du mit einem Tauchgang in sehr flachem Wasser, damit du dich in ruhigen und einfachen Bedingungen an die Bewegung und das Atmen unter Wasser gew\u00f6hnen kannst.<\/p>\n\n<p>Sobald du dich wohlf\u00fchlst, setzen wir das Erlebnis in etwas tieferem Wasser fort \u2013 nat\u00fcrlich weiterhin einfach, kontrolliert und ideal f\u00fcr Anf\u00e4nger.<\/p>\n\n<p>Die lokalen Buchten sind leicht zug\u00e4nglich und voller Meeresleben \u2013 von Schw\u00e4rmen kleiner Rifffische und Barrakudas bis hin zu Rochen, Nacktschnecken und sogar Engelhaien.<\/p>\n\n<h3>Dauer:<\/h3>\n<ul>\n    <li>2 Stunden<\/li>\n<\/ul>\n\n<h3>Inklusive:<\/h3>\n<ul>\n    <li>Leihausr\u00fcstung<\/li>\n    <li>Digitale Materialien<\/li>\n    <li>Tauchversicherung<\/li>\n    <li>SSI Try Scuba Anerkennung<\/li>\n<\/ul>\n\n<h3>Voraussetzungen:<\/h3>\n<ul>\n    <li>Grundlegende Schwimmf\u00e4higkeit<\/li>\n    <li>Mindestalter von 8 Jahren<\/li>\n<\/ul>\n\n<h3>Nicht inklusive:<\/h3>\n<ul>\n    <li>Unterwasserfotos (Kameraverleih auf Anfrage m\u00f6glich)<\/li>\n<\/ul>\n\n<h3>Weitere Kurse, die dich interessieren k\u00f6nnten:<\/h3>\n<ul>\n    <li><a href=\"https:\/\/calerodiving.com\/de\/basic-diver\/\">Basic Diver<\/a><\/li>\n    <li><a href=\"https:\/\/calerodiving.com\/de\/ssi-open-water-diver\/\">Open Water Diver<\/a><\/li>\n<\/ul>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b30fb1a e-con-full e-flex e-con e-child\" data-id=\"b30fb1a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b6364ee e-con-full course-sidebar-box e-flex e-con e-child\" data-id=\"b6364ee\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:110,&quot;sticky_effects_offset&quot;:130,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d578bfa elementor-widget elementor-widget-text-editor\" data-id=\"d578bfa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"courses-info\"><h6 class=\"no-margin\">Dauer:<\/h6><p class=\"no-margin\">2 Stunden Kurs<\/p><\/div><div class=\"courses-info\"><h6 class=\"no-margin\">Preis:<\/h6><p class=\"no-margin\">Ab 95 \u20ac<\/p><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7038662 elementor-mobile-align-center elementor-widget elementor-widget-button\" data-id=\"7038662\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/booking.calerodiving.com\/front\/6213b2319a1bbf005fa0b870\/product\/621912b69a1bbf005fa0c479?lang=dehttps:\/\/booking.calerodiving.com\/front\/6213b2319a1bbf005fa0b870\/product\/621912b69a1bbf005fa0c479?lang=de\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kurs buchen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Anf\u00e4ngerkurse Try Scuba Diving Dein erster Schritt in die Unterwasserwelt. Programm\u00fcbersicht: SSI Try Scuba ist das perfekte erste Taucherlebnis \u2013 dein allererstes Mal unter Wasser und sehr wahrscheinlich nicht dein letztes. Wir zeigen dir die Tauchausr\u00fcstung, erkl\u00e4ren dir die wichtigsten Grundregeln des Ger\u00e4tetauchens und die wichtigsten Unterwasser-Handzeichen. Nach der Einf\u00fchrung startest du mit einem Tauchgang [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-24883","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Try Scuba Diving | Calero Diving Lanzarote<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/calerodiving.com\/try-scuba-diving\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Try Scuba Diving | Calero Diving Lanzarote\" \/>\n<meta property=\"og:description\" content=\"Anf\u00e4ngerkurse Try Scuba Diving Dein erster Schritt in die Unterwasserwelt. Programm\u00fcbersicht: SSI Try Scuba ist das perfekte erste Taucherlebnis \u2013 dein allererstes Mal unter Wasser und sehr wahrscheinlich nicht dein letztes. Wir zeigen dir die Tauchausr\u00fcstung, erkl\u00e4ren dir die wichtigsten Grundregeln des Ger\u00e4tetauchens und die wichtigsten Unterwasser-Handzeichen. Nach der Einf\u00fchrung startest du mit einem Tauchgang [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/calerodiving.com\/try-scuba-diving\/\" \/>\n<meta property=\"og:site_name\" content=\"Calero Diving Lanzarote\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/calerodiving\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-10T09:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/calerodiving.com\\\/try-scuba-diving\\\/\",\"url\":\"https:\\\/\\\/calerodiving.com\\\/try-scuba-diving\\\/\",\"name\":\"Try Scuba Diving | Calero Diving Lanzarote\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/calerodiving.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/calerodiving.com\\\/try-scuba-diving\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/calerodiving.com\\\/try-scuba-diving\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/calerodiving.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG_0464divers-1030x687.jpg\",\"datePublished\":\"2025-09-01T12:29:09+00:00\",\"dateModified\":\"2026-06-10T09:52:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/calerodiving.com\\\/try-scuba-diving\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/calerodiving.com\\\/try-scuba-diving\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/calerodiving.com\\\/try-scuba-diving\\\/#primaryimage\",\"url\":\"https:\\\/\\\/calerodiving.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG_0464divers-1030x687.jpg\",\"contentUrl\":\"https:\\\/\\\/calerodiving.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/IMG_0464divers-1030x687.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/calerodiving.com\\\/try-scuba-diving\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/calerodiving.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Try Scuba Diving\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/calerodiving.com\\\/#website\",\"url\":\"https:\\\/\\\/calerodiving.com\\\/\",\"name\":\"Calero Diving Lanzarote\",\"description\":\"Dive Center - Marina Puerto Calero Lanzarote\",\"publisher\":{\"@id\":\"https:\\\/\\\/calerodiving.com\\\/#organization\"},\"alternateName\":\"Calero Diving\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/calerodiving.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/calerodiving.com\\\/#organization\",\"name\":\"Calero Diving Lanzarote\",\"alternateName\":\"Calero Diving\",\"url\":\"https:\\\/\\\/calerodiving.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/calerodiving.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/calerodiving.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Grupo.png\",\"contentUrl\":\"https:\\\/\\\/calerodiving.com\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/Grupo.png\",\"width\":499,\"height\":590,\"caption\":\"Calero Diving Lanzarote\"},\"image\":{\"@id\":\"https:\\\/\\\/calerodiving.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/calerodiving\\\/\",\"https:\\\/\\\/www.instagram.com\\\/calerodiving\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Try Scuba Diving | Calero Diving Lanzarote","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/calerodiving.com\/try-scuba-diving\/","og_locale":"de_DE","og_type":"article","og_title":"Try Scuba Diving | Calero Diving Lanzarote","og_description":"Anf\u00e4ngerkurse Try Scuba Diving Dein erster Schritt in die Unterwasserwelt. Programm\u00fcbersicht: SSI Try Scuba ist das perfekte erste Taucherlebnis \u2013 dein allererstes Mal unter Wasser und sehr wahrscheinlich nicht dein letztes. Wir zeigen dir die Tauchausr\u00fcstung, erkl\u00e4ren dir die wichtigsten Grundregeln des Ger\u00e4tetauchens und die wichtigsten Unterwasser-Handzeichen. Nach der Einf\u00fchrung startest du mit einem Tauchgang [&hellip;]","og_url":"https:\/\/calerodiving.com\/try-scuba-diving\/","og_site_name":"Calero Diving Lanzarote","article_publisher":"https:\/\/www.facebook.com\/calerodiving\/","article_modified_time":"2026-06-10T09:52:31+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/calerodiving.com\/try-scuba-diving\/","url":"https:\/\/calerodiving.com\/try-scuba-diving\/","name":"Try Scuba Diving | Calero Diving Lanzarote","isPartOf":{"@id":"https:\/\/calerodiving.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/calerodiving.com\/try-scuba-diving\/#primaryimage"},"image":{"@id":"https:\/\/calerodiving.com\/try-scuba-diving\/#primaryimage"},"thumbnailUrl":"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-1030x687.jpg","datePublished":"2025-09-01T12:29:09+00:00","dateModified":"2026-06-10T09:52:31+00:00","breadcrumb":{"@id":"https:\/\/calerodiving.com\/try-scuba-diving\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/calerodiving.com\/try-scuba-diving\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/calerodiving.com\/try-scuba-diving\/#primaryimage","url":"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-1030x687.jpg","contentUrl":"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/07\/IMG_0464divers-1030x687.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/calerodiving.com\/try-scuba-diving\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/calerodiving.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Try Scuba Diving"}]},{"@type":"WebSite","@id":"https:\/\/calerodiving.com\/#website","url":"https:\/\/calerodiving.com\/","name":"Calero Diving Lanzarote","description":"Dive Center - Marina Puerto Calero Lanzarote","publisher":{"@id":"https:\/\/calerodiving.com\/#organization"},"alternateName":"Calero Diving","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/calerodiving.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/calerodiving.com\/#organization","name":"Calero Diving Lanzarote","alternateName":"Calero Diving","url":"https:\/\/calerodiving.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/calerodiving.com\/#\/schema\/logo\/image\/","url":"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/05\/Grupo.png","contentUrl":"https:\/\/calerodiving.com\/wp-content\/uploads\/2025\/05\/Grupo.png","width":499,"height":590,"caption":"Calero Diving Lanzarote"},"image":{"@id":"https:\/\/calerodiving.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/calerodiving\/","https:\/\/www.instagram.com\/calerodiving\/"]}]}},"_links":{"self":[{"href":"https:\/\/calerodiving.com\/de\/wp-json\/wp\/v2\/pages\/24883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/calerodiving.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/calerodiving.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/calerodiving.com\/de\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/calerodiving.com\/de\/wp-json\/wp\/v2\/comments?post=24883"}],"version-history":[{"count":29,"href":"https:\/\/calerodiving.com\/de\/wp-json\/wp\/v2\/pages\/24883\/revisions"}],"predecessor-version":[{"id":31317,"href":"https:\/\/calerodiving.com\/de\/wp-json\/wp\/v2\/pages\/24883\/revisions\/31317"}],"wp:attachment":[{"href":"https:\/\/calerodiving.com\/de\/wp-json\/wp\/v2\/media?parent=24883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}